{"id":7095,"date":"2024-03-29T19:09:09","date_gmt":"2024-03-29T22:09:09","guid":{"rendered":"https:\/\/saintandrews.com.br\/?post_type=product&#038;p=7095"},"modified":"2026-04-30T18:47:32","modified_gmt":"2026-04-30T21:47:32","slug":"massage-anti-stress","status":"publish","type":"product","link":"https:\/\/saintandrews.com.br\/fr\/produto\/massagem-anti-stress\/","title":{"rendered":"Massage anti-stress"},"content":{"rendered":"<p>Massage id\u00e9al pour procurer une grande sensation de confort, un soulagement des douleurs musculaires et un soulagement du stress.<\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">***<\/span><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><em><span style=\"color: #993300;\">Apr\u00e8s avoir achet\u00e9 un service aupr\u00e8s de Saint Andrews et confirm\u00e9 le paiement, l&#039;un de nos concierges d\u00e9di\u00e9s vous contactera par t\u00e9l\u00e9phone pour vous informer des cr\u00e9neaux horaires disponibles \u00e0 la date choisie, vous assurant ainsi une r\u00e9servation avec un maximum de confort et d&#039;exclusivit\u00e9.<\/span><\/em><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Massage id\u00e9al pour procurer une grande sensation de confort, un soulagement des douleurs musculaires et un soulagement du stress.<\/p>","protected":false},"featured_media":10059,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[230],"product_tag":[],"class_list":{"0":"post-7095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-spa","8":"first","9":"instock","10":"virtual","11":"sold-individually","12":"taxable","13":"purchasable","14":"product-type-booking"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Massagem Anti Stress - Castelo Saint Andrews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saintandrews.com.br\/fr\/produit\/massage-anti-stress\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massagem Anti Stress - Castelo Saint Andrews\" \/>\n<meta property=\"og:description\" content=\"Massagem ideal para proporcionar grande sensa\u00e7\u00e3o de conforto, al\u00edvio de dores musculares e melhora do stress.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saintandrews.com.br\/fr\/produit\/massage-anti-stress\/\" \/>\n<meta property=\"og:site_name\" content=\"Castelo Saint Andrews\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T21:47:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/03\/asal-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/\",\"url\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/\",\"name\":\"Massagem Anti Stress - Castelo Saint Andrews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saintandrews.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/asal-5.png\",\"datePublished\":\"2024-03-29T22:09:09+00:00\",\"dateModified\":\"2026-04-30T21:47:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saintandrews.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/asal-5.png\",\"contentUrl\":\"https:\\\/\\\/saintandrews.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/asal-5.png\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/produto\\\/massagem-anti-stress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/saintandrews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experi\u00eancias\",\"item\":\"https:\\\/\\\/saintandrews.com.br\\\/experiencias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Massagem Anti Stress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/saintandrews.com.br\\\/\",\"name\":\"Castelo Saint Andrews\",\"description\":\"Seu hotel\u00a0em\u00a0Gramado\",\"publisher\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saintandrews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#organization\",\"name\":\"Castelo Saint Andrews\",\"url\":\"https:\\\/\\\/saintandrews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/saintandrews.com.br\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-SaintAndrews-Cabecalho-01-01.svg\",\"contentUrl\":\"https:\\\/\\\/saintandrews.com.br\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-SaintAndrews-Cabecalho-01-01.svg\",\"width\":612.8999999999999772626324556767940521240234375,\"height\":167.5,\"caption\":\"Castelo Saint Andrews\"},\"image\":{\"@id\":\"https:\\\/\\\/saintandrews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massage anti-stress - Ch\u00e2teau de Saint Andrews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saintandrews.com.br\/fr\/produit\/massage-anti-stress\/","og_locale":"fr_FR","og_type":"article","og_title":"Massagem Anti Stress - Castelo Saint Andrews","og_description":"Massagem ideal para proporcionar grande sensa\u00e7\u00e3o de conforto, al\u00edvio de dores musculares e melhora do stress.","og_url":"https:\/\/saintandrews.com.br\/fr\/produit\/massage-anti-stress\/","og_site_name":"Castelo Saint Andrews","article_modified_time":"2026-04-30T21:47:32+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/03\/asal-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/","url":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/","name":"Massage anti-stress - Ch\u00e2teau de Saint Andrews","isPartOf":{"@id":"https:\/\/saintandrews.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/#primaryimage"},"image":{"@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/#primaryimage"},"thumbnailUrl":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/03\/asal-5.png","datePublished":"2024-03-29T22:09:09+00:00","dateModified":"2026-04-30T21:47:32+00:00","breadcrumb":{"@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/#primaryimage","url":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/03\/asal-5.png","contentUrl":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/03\/asal-5.png","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/saintandrews.com.br\/produto\/massagem-anti-stress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/saintandrews.com.br\/"},{"@type":"ListItem","position":2,"name":"Experi\u00eancias","item":"https:\/\/saintandrews.com.br\/experiencias\/"},{"@type":"ListItem","position":3,"name":"Massagem Anti Stress"}]},{"@type":"WebSite","@id":"https:\/\/saintandrews.com.br\/#website","url":"https:\/\/saintandrews.com.br\/","name":"Ch\u00e2teau de Saint Andrews","description":"Votre h\u00f4tel \u00e0 Gramado","publisher":{"@id":"https:\/\/saintandrews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saintandrews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/saintandrews.com.br\/#organization","name":"Ch\u00e2teau de Saint Andrews","url":"https:\/\/saintandrews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/saintandrews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/04\/Logo-SaintAndrews-Cabecalho-01-01.svg","contentUrl":"https:\/\/saintandrews.com.br\/wp-content\/uploads\/2024\/04\/Logo-SaintAndrews-Cabecalho-01-01.svg","width":612.8999999999999772626324556767940521240234375,"height":167.5,"caption":"Castelo Saint Andrews"},"image":{"@id":"https:\/\/saintandrews.com.br\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:12:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"product_brand","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/product\/7095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/media\/10059"}],"wp:attachment":[{"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/media?parent=7095"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/product_brand?post=7095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/product_cat?post=7095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saintandrews.com.br\/fr\/wp-json\/wp\/v2\/product_tag?post=7095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}